{"id":118,"date":"2020-12-07T06:57:12","date_gmt":"2020-12-07T06:57:12","guid":{"rendered":"http:\/\/vsk.selfhost.co\/wordpress\/?page_id=118"},"modified":"2020-12-12T08:08:41","modified_gmt":"2020-12-12T08:08:41","slug":"m81","status":"publish","type":"page","link":"http:\/\/vsk.selfhost.co\/wordpress\/index.php\/m81\/","title":{"rendered":"M81"},"content":{"rendered":"\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong><span class=\"has-inline-color has-white-color\">Name<\/span><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\">M81, Bodes Galaxie<\/td><\/tr><tr><td><strong><span class=\"has-inline-color has-white-color\">Typ<\/span><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\">Spiralgalaxie<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/vsk.selfhost.co\/wordpress\/wp-content\/uploads\/2020\/12\/m81-1.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"575\" src=\"http:\/\/vsk.selfhost.co\/wordpress\/wp-content\/uploads\/2020\/12\/m81-1-1024x575.jpg\" alt=\"\" class=\"wp-image-119\" srcset=\"http:\/\/vsk.selfhost.co\/wordpress\/wp-content\/uploads\/2020\/12\/m81-1-1024x575.jpg 1024w, http:\/\/vsk.selfhost.co\/wordpress\/wp-content\/uploads\/2020\/12\/m81-1-300x168.jpg 300w, http:\/\/vsk.selfhost.co\/wordpress\/wp-content\/uploads\/2020\/12\/m81-1-768x431.jpg 768w, http:\/\/vsk.selfhost.co\/wordpress\/wp-content\/uploads\/2020\/12\/m81-1-1536x862.jpg 1536w, http:\/\/vsk.selfhost.co\/wordpress\/wp-content\/uploads\/2020\/12\/m81-1-676x380.jpg 676w, http:\/\/vsk.selfhost.co\/wordpress\/wp-content\/uploads\/2020\/12\/m81-1.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong><span class=\"has-inline-color has-white-color\">Internet<\/span><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\"><a href=\"https:\/\/de.wikipedia.org\/wiki\/Messier_81\">Wikipedia<\/a><\/td><\/tr><tr><td><strong><span class=\"has-inline-color has-white-color\">Entfernung<\/span><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\">12 Mio Lj<\/td><\/tr><tr><td><strong><span class=\"has-inline-color has-white-color\">Durchmesser<\/span><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\">95000 Lj<\/td><\/tr><tr><td><strong><span class=\"has-inline-color has-white-color\">Entdeckung<\/span><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\">Johann Elert Bode , 31. Dezember 1774<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong><span style=\"color:#ff0004\" class=\"has-inline-color\">Aufnahmedetails<\/span><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\"><\/td><\/tr><tr><td><strong><span class=\"has-inline-color has-white-color\">Ort<\/span><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\">Sternwarte Kirchheim<\/td><\/tr><tr><td><strong><span class=\"has-inline-color has-white-color\">Datum<\/span><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\">09.2020<\/td><\/tr><tr><td><strong><span class=\"has-inline-color has-white-color\">Autor<\/span><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\">W. Grimm<\/td><\/tr><tr><td><strong><span class=\"has-inline-color has-white-color\">Teleskop<\/span><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\">60cm Spiegel<\/td><\/tr><tr><td><strong><span class=\"has-inline-color has-white-color\">Kamera<\/span><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\">EOS 6D Mark II \/ astromodifiziert<\/td><\/tr><tr><td><strong><span class=\"has-inline-color has-white-color\">Belichtung<\/span><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\">90x10s ISO 4000<\/td><\/tr><tr><td><strong><span class=\"has-inline-color has-white-color\">Bearbeitung<\/span><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\">PixInsight, Photoshop<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div class=\"wp-block-buttons\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"http:\/\/vsk.selfhost.co\/wordpress\/index.php\/messier\/\"><strong>Zur\u00fcck<\/strong><\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Name M81, Bodes Galaxie Typ Spiralgalaxie Internet Wikipedia Entfernung 12 Mio Lj Durchmesser 95000 Lj Entdeckung Johann Elert Bode , 31. Dezember 1774 Aufnahmedetails Ort Sternwarte Kirchheim Datum 09.2020 Autor W. Grimm Teleskop 60cm Spiegel Kamera EOS 6D Mark II \/ astromodifiziert Belichtung 90x10s ISO 4000 Bearbeitung PixInsight, Photoshop<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"http:\/\/vsk.selfhost.co\/wordpress\/index.php\/wp-json\/wp\/v2\/pages\/118"}],"collection":[{"href":"http:\/\/vsk.selfhost.co\/wordpress\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/vsk.selfhost.co\/wordpress\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/vsk.selfhost.co\/wordpress\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/vsk.selfhost.co\/wordpress\/index.php\/wp-json\/wp\/v2\/comments?post=118"}],"version-history":[{"count":4,"href":"http:\/\/vsk.selfhost.co\/wordpress\/index.php\/wp-json\/wp\/v2\/pages\/118\/revisions"}],"predecessor-version":[{"id":367,"href":"http:\/\/vsk.selfhost.co\/wordpress\/index.php\/wp-json\/wp\/v2\/pages\/118\/revisions\/367"}],"wp:attachment":[{"href":"http:\/\/vsk.selfhost.co\/wordpress\/index.php\/wp-json\/wp\/v2\/media?parent=118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}